{"id":1637,"date":"2023-02-13T07:00:00","date_gmt":"2023-02-13T06:00:00","guid":{"rendered":"https:\/\/www.corunning.fr\/blog\/?p=1637"},"modified":"2023-02-15T14:08:33","modified_gmt":"2023-02-15T13:08:33","slug":"reprendre-le-sport-apres-un-accouchement","status":"publish","type":"post","link":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/","title":{"rendered":"Reprendre le sport apr\u00e8s un accouchement"},"content":{"rendered":"\n<p>Que ce soit pour perdre les kilos de la grossesse, avoir son corps d&rsquo;avant ou pour le bien-\u00eatre, reprendre le sport apr\u00e8s un accouchement doit se faire en toute s\u00e9curit\u00e9 ! <\/p>\n\n\n\n<p>Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, et avec quel sport commencer ? Toutes les jeunes mamans se posent la question !<\/p>\n\n\n\n<p>Tout d&rsquo;abord, il est important de consulter votre m\u00e9decin ou votre sage femme avant de reprendre tout sport apr\u00e8s l&rsquo;accouchement. La reprise d&rsquo;une activit\u00e9 sportive apr\u00e8s b\u00e9b\u00e9 ne peut se faire qu&rsquo;apr\u00e8s avoir proc\u00e9d\u00e9 \u00e0 une r\u00e9\u00e9ducation. Avant d\u2019attaquer une reprise d&rsquo;activit\u00e9 physique, on vous donne des conseils pour \u00e9viter tous risques.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1\u00e8re \u00e9tape incontournable : la r\u00e9\u00e9ducation<\/h3>\n\n\n\n<p>Avant m\u00eame de songer \u00e0 chausser les baskets, la priorit\u00e9 du post-partum est de remuscler abdominaux, muscles du dos et p\u00e9rin\u00e9e. Il ne faut pas n\u00e9gliger non plus les articulations qui ont souffert de la fonte musculaire et de la prise de poids. Il faut donc les gainer.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">R\u00e9\u00e9ducation p\u00e9rin\u00e9ale<\/h4>\n\n\n\n<p>La reprise du sport apr\u00e8s un accouchement ne peut se faire sans une r\u00e9\u00e9ducation pr\u00e9alable.  Les muscles du plancher pelvien et les abdominaux on \u00e9t\u00e9 \u00e9tir\u00e9s et mis \u00e0 rude \u00e9preuve pendant 9 mois. Muscles et tissus sont tr\u00e8s sollicit\u00e9s tout au long de la grossesse et pour mettre au monde votre b\u00e9b\u00e9. Ces muscles doivent \u00eatre tonifi\u00e9s avant de reprendre toute activit\u00e9 physique. <\/p>\n\n\n\n<p>La r\u00e9\u00e9ducation p\u00e9rin\u00e9ale tonifie les muscles du plancher pelvien et le p\u00e9rin\u00e9e. A terme, cela pr\u00e9vient l&rsquo;incontinence urinaire voire la descente d&rsquo;organe ou prolapsus. <\/p>\n\n\n\n<p>Sage-femme ou gyn\u00e9cologue seront les plus \u00e0 m\u00eame pour vous indiquer la r\u00e9\u00e9ducation la plus adapt\u00e9e, en fonction de votre grossesse et de votre accouchement.<\/p>\n\n\n\n<p>La r\u00e9\u00e9ducation p\u00e9rin\u00e9ale peut g\u00e9n\u00e9ralement d\u00e9marrer entre 6 \u00e0 8 semaines apr\u00e8s l&rsquo;accouchement, sous prescription m\u00e9dicale. Si la d\u00e9buter trop t\u00f4t n&rsquo;est pas conseill\u00e9, en revanche, il n&rsquo;est jamais trop tard pour commencer la r\u00e9\u00e9ducation p\u00e9rin\u00e9ale ! Donc au moindre doute, demandez conseil \u00e0 un professionnel de sant\u00e9.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Muscler la sangle abdominale<\/h4>\n\n\n\n<p>Le ventre a grossi, les muscles abdominaux se sont \u00e9tir\u00e9s&nbsp;pour s&rsquo;adapter. Apr\u00e8s l&rsquo;accouchement les muscles de la sangle abdominale (transverses, obliques et grands droits (les fameuses tablettes de chocolat) doivent reprendre leur place.&nbsp;Une r\u00e9\u00e9ducation de la sangle abdominale vous aidera \u00e0 avoir une meilleure posture, un meilleur gainage. Cela augmentera \u00e9galement la vigilance sur le port des charges lourdes, notamment au quotidien.  Porter le cosy, porter b\u00e9b\u00e9, soulever un pack de bouteilles d&rsquo;eau peuvent accentuer ou cr\u00e9er une blessure.<\/p>\n\n\n\n<p>Renforcer les muscles profonds des abdominaux (transverses), et les muscles superficiels (grands droits), aide \u00e0 retrouver un ventre plat apr\u00e8s la grossesse. R\u00e9\u00e9duquer la sangle abdominale \u00e9vite aussi le mal de dos et est donc fortement pr\u00e9conis\u00e9 pour une reprise du sport apr\u00e8s b\u00e9b\u00e9.<\/p>\n\n\n\n<p>Les exercices abdominaux doivent avoir 3 composantes :&nbsp;la contraction, la respiration et le ventre qui rentre. Sans ces 3 composantes, l&rsquo;exercice n&rsquo;est pas efficace.<\/p>\n\n\n\n<p>Les mouvements en ciseaux doivent \u00eatre r\u00e9alis\u00e9s avec un bon gainage. Si le ventre et le dos bougent, c&rsquo;est que l&rsquo;exercice n&rsquo;est pas encore adapt\u00e9 et qu&rsquo;il faut renforcer les muscles du plancher pelvien.<\/p>\n\n\n\n<p>Privil\u00e9giez les abdominaux hypopressifs, qui ne soumettent pas de pression sur l&rsquo;abdomen, m\u00eame s&rsquo;ils sont d\u00e9conseill\u00e9s pour certaines jeunes mamans. Les \u00ab&nbsp;bons abdos&nbsp;\u00bb se concentrent sur le travail du transverse, favorisent l\u2019auto-agrandissement et l\u2019engagement du p\u00e9rin\u00e9e.&nbsp;<\/p>\n\n\n\n<p>Veillez l\u00e0 encore \u00e0 suivre les conseils de professionnels.\u00a0<\/p>\n\n\n\n<p>Une fois que vous aurez un plancher pelvien en b\u00e9ton et des abdos renforc\u00e9s, la reprise du sport peut se faire ! Mais attention, la reprise doit tout de m\u00eame \u00eatre progressive.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/girl-3596023_1280-1024x683.jpg\" alt=\"Reprendre le sport apr\u00e8s un accouchement\" class=\"wp-image-1655\" srcset=\"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/girl-3596023_1280-1024x683.jpg 1024w, https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/girl-3596023_1280-300x200.jpg 300w, https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/girl-3596023_1280-768x512.jpg 768w, https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/girl-3596023_1280-560x374.jpg 560w, https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/girl-3596023_1280.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Reprendre le sport apr\u00e8s un accouchement<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Quand se remettre au sport apr\u00e8s b\u00e9b\u00e9 ?<\/h3>\n\n\n\n<p>Il faut tout d&rsquo;abord pr\u00e9ciser que le d\u00e9lai pour se remettre au sport apr\u00e8s avoir accoucher d\u00e9pend de chaque femme, de sa condition physique avant, pendant et apr\u00e8s la grossesse.<\/p>\n\n\n\n<p>La reprise se doit avant tout d&rsquo;\u00eatre progressive et une fois le feu vert donn\u00e9 par votre sage femme ou gyn\u00e9cologue.<\/p>\n\n\n\n<p>On dit souvent qu&rsquo;un accouchement est physiquement aussi \u00e9prouvant pour le corps qu&rsquo;un marathon. Donc astreignez-vous, comme les marathoniennes, \u00e0 un temps de r\u00e9cup\u00e9ration post accouchement !<\/p>\n\n\n\n<p>La reprise du sport apr\u00e8s un accouchement peut d\u00e9marrer d\u00e8s que votre condition physique et psychologique le permet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quel sport pratiquer apr\u00e8s votre accouchement ?<\/h3>\n\n\n\n<p>Pour vous sentir bien, retrouver votre forme et votre silhouette, il faut au d\u00e9but privil\u00e9gier les activit\u00e9s sportives douces, sans impact, pour m\u00e9nager votre p\u00e9rin\u00e9e, encore faible.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Apr\u00e8s b\u00e9b\u00e9 : d\u00e9marrer par une activit\u00e9 physique douce 4 \u00e0 6 semaines apr\u00e8s l&rsquo;accouchement<\/h4>\n\n\n\n<p>Apr\u00e8s l&rsquo;accouchement, vous pouvez en fait pratiquer les m\u00eames activit\u00e9s physiques que pendant la grossesse. Il faut continuer d&rsquo;\u00e9viter les activit\u00e9s avec des impacts.<\/p>\n\n\n\n<p>En bref, 4 \u00e0 6 semaines apr\u00e8s l&rsquo;accouchement, les activit\u00e9s physiques douces peuvent \u00eatre reprises. La marche (\u00e0 allure tranquille, sans d\u00e9nivel\u00e9), la natation, le cardio-poussette, le v\u00e9lo, la gymnastique douce, le Pilates ou le yoga peuvent \u00eatre pratiqu\u00e9s. <\/p>\n\n\n\n<p>Mais restez \u00e0 l&rsquo;\u00e9coute de votre corps et des sensations au niveau du plancher pelvien et du bassin<strong>.<\/strong><\/p>\n\n\n\n<p>Et multipliez les sorties sportives en poussette, prendre l&rsquo;air avec b\u00e9b\u00e9 est b\u00e9n\u00e9fique pour maman et pour b\u00e9b\u00e9 !<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Et reprendre le sport 2 \u00e0 3 mois apr\u00e8s la naissance de b\u00e9b\u00e9<\/h4>\n\n\n\n<p>Apr\u00e8s avoir fait la r\u00e9\u00e9ducation du p\u00e9rin\u00e9e et&nbsp;avoir eu le feu vert d&rsquo;un professionnel de sant\u00e9, une jeune maman peut reprendre les sports avec impact au sol : la course \u00e0 pied, la danse avec sauts, les sports collectifs, le trail, &#8230; <\/p>\n\n\n\n<p>Ne reprenez la pratique que lorsque les muscles pelviens ont repris leur tonus et si vous n&rsquo;avez pas de fuites. Car reprendre le sport apr\u00e8s b\u00e9b\u00e9 ne doit pas se faire si une incontinence urinaire persiste malgr\u00e9 la r\u00e9\u00e9ducation ! Le retour de couches est souvent la fen\u00eatre id\u00e9ale pour la reprise du sport apr\u00e8s un accouchement.<\/p>\n\n\n\n<p>Le but est de pouvoir refaire du sport sans avoir envie de faire pipi au moindre impact et sans mettre en p\u00e9ril vos organes. Donc chaque femme doit trouver son rythme, \u00e9couter son corps, et adapter la reprise \u00e0 sa condition physique. Et n&rsquo;oublions pas que la reprise du sport apr\u00e8s un accouchement, ne se fera pas de la m\u00eame fa\u00e7on si la jeune maman a continu\u00e9 \u00e0 pratiquer du sport pendant sa grossesse ou pas.<\/p>\n\n\n\n<p>Tout ce qui est entra\u00eenement plus intense et musculation doit se faire tout de m\u00eame progressivement, avec un faible impact sur le p\u00e9rin\u00e9e au d\u00e9but, pour\u00a0monter en intensit\u00e9\u00a0au fil des semaines. Car certaines activit\u00e9s sportives \u00e0 forts impacts peuvent \u00eatre traumatisantes post partum, comme l\u2019\u00e9quitation, ou celles qui engendrent le port de charges lourdes comme la musculation.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et apr\u00e8s un accouchement par c\u00e9sarienne, quand reprendre le sport ?<\/h3>\n\n\n\n<p>Apr\u00e8s un accouchement par c\u00e9sarienne, la cicatrisation des tissus prend plus de temps. La reprise du sport apr\u00e8s un accouchement par c\u00e9sarienne est plut\u00f4t \u00e0 envisager 8 \u00e0 10 semaines apr\u00e8s l&rsquo;arriv\u00e9e de b\u00e9b\u00e9.&nbsp;<\/p>\n\n\n\n<p>La reprise doit l\u00e0 aussi \u00eatre progressive. Sports doux pour commencer : marche,\u00a0yoga, \u00e9tirements, natation&#8230; Puis vous pourrez tenter l&rsquo;endurance.\u00a0Apr\u00e8s une c\u00e9sarienne, les sports avec impact ne pourront \u00eatre repris qu&rsquo;apr\u00e8s avoir termin\u00e9 la r\u00e9\u00e9ducation du p\u00e9rin\u00e9e et avec l&rsquo;accord du professionnel ayant r\u00e9alis\u00e9 cette r\u00e9\u00e9ducation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dur\u00e9e de l&rsquo;activit\u00e9 sportive <\/h3>\n\n\n\n<p>Il faut se l&rsquo;avouer, d\u00e9gager de longues plages horaires et s&rsquo;y tenir n&rsquo;est pas toujours possible avec un nourrisson ! Le planning d&rsquo;une jeune maman est souvent bien charg\u00e9&#8230;<\/p>\n\n\n\n<p>Car, r\u00e9ussir \u00e0 se d\u00e9gager des parenth\u00e8ses dans sa semaine pour faire du sport, avec ou sans b\u00e9b\u00e9, est important. <\/p>\n\n\n\n<p>N\u2019h\u00e9sitez donc pas \u00e0 vous caler des s\u00e9ances, m\u00eame courtes. 10 minutes, plusieurs fois par semaine, suffisent pour se bouger et reprendre en douceur. Et bouger un peu est mieux que ne pas bouger du tout.<\/p>\n\n\n\n<p>L&rsquo;id\u00e9al est de trouver une routine, d&rsquo;int\u00e9grer un nouveau rituel dans cette nouvelle vie de maman ou de parents. Trouvez le meilleur moment pour vous : pendant la sieste de b\u00e9b\u00e9, apr\u00e8s la t\u00e9t\u00e9e ou le biberon. Vous pouvez aussi combiner sport et balade en poussette ! B\u00e9b\u00e9 s&rsquo;endormira dans la poussette et vous prendrez un bon bol d&rsquo;air.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Quoiqu&rsquo;il en soit, restez \u00e0 l&rsquo;\u00e9coute de votre corps, des sensations, et des signes de fatigue. Ne forcez pas trop, n&rsquo;ayez pas des objectifs trop \u00e9lev\u00e9s et ne soyez pas trop press\u00e9e. Etre maman est d\u00e9j\u00e0 en soi, un sport ! Donc m\u00e9nagez vous quand c&rsquo;est n\u00e9cessaire, quand votre corps vous dit stop. Ne recherchez pas imm\u00e9diatement la performance physique. <\/p>\n\n\n\n<p>Et les jours o\u00f9 vous manquez de motivation, faites une sortie rando poussette. Proposez des sorties entre jeunes mamans via notre <a href=\"http:\/\/www.corunning.fr\" target=\"_blank\" rel=\"noreferrer noopener\">plateforme <\/a>! Faites du sport \u00e0 plusieurs, avec d&rsquo;autres mamans, encouragez vous mutuellement dans votre remise en forme et dans vos nouvelles pr\u00e9occupations de parents. <\/p>\n\n\n\n<p>Alors, pr\u00eate \u00e0&nbsp;reprendre le sport apr\u00e8s l&rsquo;accouchement&nbsp;en toute s\u00e9curit\u00e9&nbsp;?<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que ce soit pour perdre les kilos de la grossesse, avoir son corps d&rsquo;avant ou pour le bien-\u00eatre, reprendre le sport apr\u00e8s un accouchement doit se faire en toute s\u00e9curit\u00e9 ! <\/p>\n<p>Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, avec quel sport commencer ?<\/p>\n","protected":false},"author":2,"featured_media":1656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[98,1],"tags":[],"class_list":["post-1637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reprendre le sport apr\u00e8s un accouchement - Corunning<\/title>\n<meta name=\"description\" content=\"Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, avec quel sport commencer ? Reprendre le sport apr\u00e8s un accouchement en toute s\u00e9curit\u00e9 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reprendre le sport apr\u00e8s un accouchement - Corunning\" \/>\n<meta property=\"og:description\" content=\"Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, avec quel sport commencer ? Reprendre le sport apr\u00e8s un accouchement en toute s\u00e9curit\u00e9 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/\" \/>\n<meta property=\"og:site_name\" content=\"Corunning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/corunning.fr\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-13T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-15T13:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/Capture.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"698\" \/>\n\t<meta property=\"og:image:height\" content=\"289\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"magali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"magali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/\"},\"author\":{\"name\":\"magali\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#\\\/schema\\\/person\\\/70bf8e3c1989e419049c5209478a4244\"},\"headline\":\"Reprendre le sport apr\u00e8s un accouchement\",\"datePublished\":\"2023-02-13T06:00:00+00:00\",\"dateModified\":\"2023-02-15T13:08:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/\"},\"wordCount\":1647,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture.jpg\",\"articleSection\":[\"actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/\",\"url\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/\",\"name\":\"Reprendre le sport apr\u00e8s un accouchement - Corunning\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture.jpg\",\"datePublished\":\"2023-02-13T06:00:00+00:00\",\"dateModified\":\"2023-02-15T13:08:33+00:00\",\"description\":\"Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, avec quel sport commencer ? Reprendre le sport apr\u00e8s un accouchement en toute s\u00e9curit\u00e9 !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture.jpg\",\"contentUrl\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture.jpg\",\"width\":698,\"height\":289,\"caption\":\"Reprise du sport apr\u00e8s b\u00e9b\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/2023\\\/02\\\/13\\\/reprendre-le-sport-apres-un-accouchement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reprendre le sport apr\u00e8s un accouchement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/\",\"name\":\"Corunning\",\"description\":\"L&#039;appli gratuite pour sporter \u00e0 plusieurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#organization\",\"name\":\"Corunning\",\"url\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logov4.png\",\"contentUrl\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logov4.png\",\"width\":512,\"height\":512,\"caption\":\"Corunning\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/corunning.fr\",\"https:\\\/\\\/www.instagram.com\\\/corunningfr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/#\\\/schema\\\/person\\\/70bf8e3c1989e419049c5209478a4244\",\"name\":\"magali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d73b646edffe1275e96ebac7940a565359d30873f265d6a3524c6d8ec18666d0?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d73b646edffe1275e96ebac7940a565359d30873f265d6a3524c6d8ec18666d0?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d73b646edffe1275e96ebac7940a565359d30873f265d6a3524c6d8ec18666d0?s=96&d=retro&r=g\",\"caption\":\"magali\"},\"sameAs\":[\"https:\\\/\\\/www.corunning.fr\"],\"url\":\"https:\\\/\\\/www.corunning.fr\\\/blog\\\/author\\\/magali\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reprendre le sport apr\u00e8s un accouchement - Corunning","description":"Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, avec quel sport commencer ? Reprendre le sport apr\u00e8s un accouchement en toute s\u00e9curit\u00e9 !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/","og_locale":"fr_FR","og_type":"article","og_title":"Reprendre le sport apr\u00e8s un accouchement - Corunning","og_description":"Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, avec quel sport commencer ? Reprendre le sport apr\u00e8s un accouchement en toute s\u00e9curit\u00e9 !","og_url":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/","og_site_name":"Corunning","article_publisher":"https:\/\/www.facebook.com\/corunning.fr","article_published_time":"2023-02-13T06:00:00+00:00","article_modified_time":"2023-02-15T13:08:33+00:00","og_image":[{"width":698,"height":289,"url":"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/Capture.jpg","type":"image\/jpeg"}],"author":"magali","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"magali","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#article","isPartOf":{"@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/"},"author":{"name":"magali","@id":"https:\/\/www.corunning.fr\/blog\/#\/schema\/person\/70bf8e3c1989e419049c5209478a4244"},"headline":"Reprendre le sport apr\u00e8s un accouchement","datePublished":"2023-02-13T06:00:00+00:00","dateModified":"2023-02-15T13:08:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/"},"wordCount":1647,"commentCount":0,"publisher":{"@id":"https:\/\/www.corunning.fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/Capture.jpg","articleSection":["actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/","url":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/","name":"Reprendre le sport apr\u00e8s un accouchement - Corunning","isPartOf":{"@id":"https:\/\/www.corunning.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#primaryimage"},"image":{"@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/Capture.jpg","datePublished":"2023-02-13T06:00:00+00:00","dateModified":"2023-02-15T13:08:33+00:00","description":"Quand se remettre au sport apr\u00e8s avoir eu un b\u00e9b\u00e9, avec quel sport commencer ? Reprendre le sport apr\u00e8s un accouchement en toute s\u00e9curit\u00e9 !","breadcrumb":{"@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#primaryimage","url":"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/Capture.jpg","contentUrl":"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2023\/02\/Capture.jpg","width":698,"height":289,"caption":"Reprise du sport apr\u00e8s b\u00e9b\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.corunning.fr\/blog\/2023\/02\/13\/reprendre-le-sport-apres-un-accouchement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.corunning.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Reprendre le sport apr\u00e8s un accouchement"}]},{"@type":"WebSite","@id":"https:\/\/www.corunning.fr\/blog\/#website","url":"https:\/\/www.corunning.fr\/blog\/","name":"Corunning","description":"L&#039;appli gratuite pour sporter \u00e0 plusieurs","publisher":{"@id":"https:\/\/www.corunning.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.corunning.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.corunning.fr\/blog\/#organization","name":"Corunning","url":"https:\/\/www.corunning.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.corunning.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2024\/03\/logov4.png","contentUrl":"https:\/\/www.corunning.fr\/blog\/wp-content\/uploads\/2024\/03\/logov4.png","width":512,"height":512,"caption":"Corunning"},"image":{"@id":"https:\/\/www.corunning.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/corunning.fr","https:\/\/www.instagram.com\/corunningfr\/"]},{"@type":"Person","@id":"https:\/\/www.corunning.fr\/blog\/#\/schema\/person\/70bf8e3c1989e419049c5209478a4244","name":"magali","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d73b646edffe1275e96ebac7940a565359d30873f265d6a3524c6d8ec18666d0?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d73b646edffe1275e96ebac7940a565359d30873f265d6a3524c6d8ec18666d0?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d73b646edffe1275e96ebac7940a565359d30873f265d6a3524c6d8ec18666d0?s=96&d=retro&r=g","caption":"magali"},"sameAs":["https:\/\/www.corunning.fr"],"url":"https:\/\/www.corunning.fr\/blog\/author\/magali\/"}]}},"_links":{"self":[{"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/posts\/1637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":8,"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/posts\/1637\/revisions"}],"predecessor-version":[{"id":1659,"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/posts\/1637\/revisions\/1659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/media\/1656"}],"wp:attachment":[{"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/media?parent=1637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/categories?post=1637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corunning.fr\/blog\/wp-json\/wp\/v2\/tags?post=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}